{"id":297,"date":"2023-05-03T11:21:56","date_gmt":"2023-05-03T10:21:56","guid":{"rendered":"https:\/\/www.polarisshop.ch\/?page_id=297"},"modified":"2023-09-15T15:00:10","modified_gmt":"2023-09-15T14:00:10","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"297\" class=\"elementor elementor-297\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c16bc83 elementor-section-boxed elementor-section-gap-beside-yes elementor-section-height-default elementor-section-height-default elementor-section-column-vertical-align-stretch\" data-id=\"c16bc83\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d665edf\" data-id=\"d665edf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-311e707 elementor-widget elementor-widget-tm-heading\" data-id=\"311e707\" data-element_type=\"widget\" data-widget_type=\"tm-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tm-modern-heading tm-modern-heading--highlight-style-01\">\n\t\t\t\n\t\t\t\t\t<div class=\"heading-primary-wrap\">\n\t\t\t<h2 class=\"heading-primary elementor-heading-title\">Privacy policy<\/h2>\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"heading-description-wrap\">\n\t\t\t<div class=\"heading-description\">\n\t\t\t\t<p><strong>Polaris S.R.L. (nel seguito, \u201cPolaris S.R.L.\u201d) fornisce agli utenti del sito web Polaris Shop (nel seguito, il \u201cSito\u201d, visitabile all\u2019indirizzo www.polarisshop.ch) le seguenti informazioni, nel rispetto dell\u2019articolo 13 Regolamento (UE) 2016\/679 (o General Data Protection Regulation, nel seguito \u201cG.D.P.R\u201d) e successiva normativa nazionale di adeguamento (nel seguito indicata, congiuntamente al G.D.P.R., come \u201cNormativa Privacy Applicabile\u201d). Durante la consultazione del Sito vengono, infatti, raccolte informazioni relative agli utenti, che costituiscono dati personali ai sensi della Normativa Privacy applicabile.<\/strong><\/p><h3>Titolare del trattamento dei dati<\/h3><p>Titolare del trattamento dei dati personali \u00e8 Polaris S.R.L., con sede in Italia: sede legale in Via Trento, 13\/H a Sondrio (SO) e sede operativa in Via Stelvio, 24 a Poggiridenti (SO), e-mail info@polarisshop.ch e tel. +39 0342 513196.<\/p><h3>Tipi di dati trattati<\/h3><p>Di seguito sono specificati i dati che vengono trattati da Polaris S.R.L. nel caso in cui l\u2019utente utilizzi il Sito.<br \/>L'utente si assume la responsabilit\u00e0 degli eventuali dati personali di terzi inseriti o pubblicati sul Sito, e garantisce di avere il diritto di comunicarli o diffonderli - liberando cos\u00ec Polaris S.R.L. da qualsiasi responsabilit\u00e0 verso i suddetti terzi.<\/p><h4>Dati personali acquisiti automaticamente in caso di visita al Sito<\/h4><ul><li><strong>Dati sulla navigazione.<\/strong> Polaris S.R.L. raccoglie automaticamente dati sul dispositivo (pc, tablet, telefono cellulare o altro dispositivo mobile) e la connessione utilizzati dall\u2019utente, tra i quali, ad esempio, l\u2019indirizzo IP, la data e l\u2019ora di accesso, le informazioni su hardware e software, le informazioni sugli eventi riguardanti il dispositivo, gli identificativi unici, i dati di crash.<\/li><li><strong>Dati sull'utilizzo del Sito.<\/strong> Polaris S.R.L. raccoglie informazioni sulle modalit\u00e0 con le quali l\u2019utente ha utilizzato il Sito, comprese, ad esempio, le pagine del Sito o altri contenuti visualizzati, le ricerche effettuate, le applicazioni di terze parti presenti sul Sito che vengono utilizzate dall\u2019utente e i link ad altri siti e applicazioni su cui l\u2019utente ha cliccato.<\/li><\/ul><h4>Dati personali forniti direttamente dall\u2019utente<\/h4><h4>a) Dati necessari per la creazione di un account<\/h4><ul><li><strong>Dati forniti per la creazione di un account.<\/strong> Se l\u2019utente, attraverso l\u2019icona o in fase di checkout decide di registrarsi al sito, Polaris S.R.L. raccoglie nome, cognome, indirizzo e-mail.<\/li><\/ul><p>Queste informazioni sono necessarie per consentire all\u2019utente di creare un account presso Polaris S.R.L.. Se l\u2019utente non intende fornire i suddetti dati, non potr\u00e0 creare la propria area riservata.<\/p><h4>b) Dati facoltativi<\/h4><ul><li><strong>Dati forniti mediante richieste di informazioni via e-mail.<\/strong> Se l\u2019utente, per richiedere informazioni, invia in modo esplicito e volontario posta elettronica agli indirizzi di Polaris S.R.L. indicati sul Sito, oppure utilizza il modulo disponibile nella sezione del sito \u201cContatti\u201d Polaris S.R.L. acquisisce nome, cognome e indirizzo e-mail.<\/li><\/ul><h3>Finalit\u00e0 di trattamento<\/h3><p><strong>Contribuire al funzionamento del Sito; fornire all\u2019utente i servizi che Polaris S.R.L. presta tramite il Sito; proteggere gli interessi vitali dell\u2019utente; rispettare la normativa vigente o perseguire altre esigenze di interesse pubblico<\/strong><\/p><p>I dati dell\u2019utente, infatti, vengono trattati:<\/p><ul><li>per far funzionare, misurare, migliorare e mantenere sicuri il Sito e i servizi resi tramite esso;<\/li><li>per prevenire, rilevare e mitigare violazioni della sicurezza e attivit\u00e0 potenzialmente vietate o illegali.<\/li><\/ul><p><strong>Perseguire i legittimi interessi di Polaris S.R.L. in modo tale che questi interessi non prevalgano sui diritti e sulle libert\u00e0 fondamentali dell\u2019utente<\/strong><\/p><p>I dati dell\u2019utente, infatti, vengono trattati:<\/p><ul><li>per identificare e risolvere i problemi riscontrati dall\u2019utente nell\u2019utilizzo del Sito (ad esempio, pagine bloccate o non funzionanti).<\/li><\/ul><p>Questi trattamenti tutelano l\u2019interesse di Polaris S.R.L. a mantenere il Sito funzionante ed efficiente. Essi, inoltre, non ledono i diritti e le libert\u00e0 fondamentali dell\u2019utente, in quanto sono trattamenti prevedibili e diffusi in ogni sito che permetta la creazione di account. Inoltre, tali trattamenti vanno altres\u00ec a vantaggio dell\u2019utente stesso, permettendo al Sito di continuare a funzionare.<\/p><h3>Social button<\/h3><p>Il Sito utilizza diversi link, che permettono agli utenti di visitare i profili Facebook e Instagram di Polaris Shop (vedi footer del Sito). Questi link - che si presentano come icone dei relativi social networks - non comportano l\u2019installazione di cookie di terze parti.<\/p><h3>Modalit\u00e0 di trattamento<\/h3><p>I dati personali dell\u2019utente sono trattati con strumenti, informatici o telematici, esclusivamente per le finalit\u00e0 per le quali sono stati raccolti (vedi sopra), e conservati per un periodo determinato secondo i criteri segnalati in questa privacy policy (vedi sotto).<br \/>I dati personali potranno essere conosciuti e trattati dal personale di Polaris S.R.L., debitamente istruito circa le cautele da adottare previste dalla Normativa Privacy applicabile.<\/p><h3>Durata di trattamento<\/h3><p>Gli specifici tempi di conservazione dei dati personali dell\u2019utente sono documentati nel registro delle attivit\u00e0 di trattamento di Polaris S.R.L. (implementato ai sensi dell\u2019articolo 30 della G.D.P.R.).<br \/>I dati personali dell\u2019utente vengono conservati (secondo i criteri di cui al considerando 39 e all\u2019art. 5, comma 1, lett. e) del G.D.P.R.) per un periodo necessario ad assicurare che il Sito funzioni, e che Polaris S.R.L. eroghi agli utenti i servizi prestati tramite il Sito. Tale periodo, in ogni caso, non pu\u00f2 eccedere i 10 anni dalla raccolta.<br \/>I dati personali dell\u2019utente possono essere conservati per periodi maggiori di quelli appena visti solamente nel caso in ci\u00f2 sia necessario a Polaris S.R.L. per assolvere gli obblighi di legge ricadenti in capo ad essi o per tutelare un diritto in sede giudiziaria.<br \/>Alla scadenza di tali termini di conservazione, i dati dell\u2019utente vengono cancellati, oppure resi anonimi in modo permanente.<\/p><h3>Comunicazione dei dati<\/h3><p>Polaris S.R.L. potrebbe comunicare i dati personali trattati ai soli soggetti e per le sole finalit\u00e0 di seguito indicati.<\/p><h4>Lotta agli atti illeciti e alle violazioni di sicurezza<\/h4><ul><li>Polaris S.R.L. potrebbe comunicare i dati personali degli utenti a soggetti terzi che si occupano di prevenire, rilevare e mitigare atti potenzialmente illeciti e violazioni della sicurezza.<\/li><\/ul><h4>Applicazione della legge, procedimenti giudiziari e modalit\u00e0 autorizzate dalla legge italiana<\/h4><ul><li>Polaris S.R.L. potrebbe comunicare i dati personali degli utenti ad Autorit\u00e0 Giudiziarie, Pubbliche Autorit\u00e0 o terze parti autorizzate, nei casi in cui la legge lo prevede. Nonch\u00e9, in generale, nei casi in cui sia necessario per adempiere obblighi di legge o richieste verificate relative ad un'indagine penale o ad una presunta attivit\u00e0 illecita, oppure per rispondere a rivendicazioni altrui circa i diritti, la propriet\u00e0 o la sicurezza di Polaris S.R.L., dei suoi dipendenti o degli utenti.<\/li><\/ul><h3>Diritti degli interessati<\/h3><p>Nei soli casi e con tutti i limiti previsti dagli artt. 15-22 G.D.P.R., in ogni momento, a titolo gratuito e senza oneri e formalit\u00e0 particolari, l\u2019utente ha diritto a:<\/p><ul><li>ottenere conferma del fatto che Polaris S.R.L. tratta i suoi dati personali;<\/li><li>accedere ai suoi dati personali, e conoscerne l\u2019origine, le finalit\u00e0 e gli scopi di trattamento, il periodo di conservazione e le informazioni riguardanti i soggetti terzi cui i dati personali vengono comunicati;<\/li><li>revocare il suo consenso in qualunque momento, nel caso in cui questo costituisca la base del trattamento;<\/li><li>aggiornare o rettificare i suoi dati personali raccolti da Polaris S.R.L., in modo che questi ultimi siano sempre esatti e accurati;<\/li><li>esercitare il cd. diritto all\u2019oblio, ovvero fare in modo che i suoi dati personali raccolti da Polaris S.R.L. vengano cancellati dalle banche dati e\/o dagli archivi anche di backup di Polaris S.R.L.;<\/li><li>limitare il trattamento dei suoi dati personali da parte di Polaris S.R.L.;<\/li><li>opporsi al trattamento, per quei dati personali trattati per perseguire esigenze di interesse pubblico oppure legittimi interessi di Polaris S.R.L.;<\/li><li>vedersi comunicate, in tempi congrui, le eventuali rettifiche, cancellazioni o limitazioni del trattamento disposte da Polaris S.R.L., nonch\u00e9 le eventuali revoche di tali misure e le ragioni alla base delle revoche.<\/li><\/ul><p>L\u2019utente pu\u00f2 esercitare tali diritti mediante richiesta scritta rivolta senza formalit\u00e0 a Polaris S.R.L., inviando apposita e-mail all\u2019indirizzo dpo@webtek.it.<br \/>Una volta ricevuta la suddetta e-mail, Polaris S.R.L. soddisfer\u00e0 la richiesta entro un mese dal ricevimento della stessa. Tale termine potr\u00e0 essere prorogato di due mesi - previo avviso all\u2019utente - tenuto conto della complessit\u00e0 e del numero delle richieste.<br \/>Polaris S.R.L. ricorda all\u2019utente che, laddove il riscontro alle sue richieste non sia stato a suo avviso soddisfacente, egli\/ella potr\u00e0 rivolgersi e proporre reclamo all\u2019Autorit\u00e0 Garante per la Protezione dei Dati Personali (<a href=\"http:\/\/www.garanteprivacy.it\/\">http:\/\/www.garanteprivacy.it\/<\/a>) nei modi previsti dalla Normativa Privacy applicabile.<\/p><h3>Modifiche alla privacy policy<\/h3><p>Polaris S.R.L. si riserva il diritto di apportare modifiche alla presente privacy policy in qualunque momento, dandone comunicazione agli utenti su questa pagina del Sito.<br \/>Si prega, dunque, l\u2019utente di consultare spesso questa pagina, prendendo come riferimento la data di ultima modifica indicata in fondo. Salvo quanto diversamente specificato, in caso di modifica la precedente privacy policy continuer\u00e0 ad applicarsi ai dati personali sino a quel momento raccolti.<\/p><p><em>Data ultimo aggiornamento: maggio 2023<\/em><\/p><p><\/p>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a769e0 elementor-widget elementor-widget-text-editor\" data-id=\"0a769e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.0 - 08-05-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h3>Cookies<\/h3>\n<div id=\"CookieDeclaration\"><\/div>\n<script>!function(de,cl,ar,at,i,o,n){\nlet a=de.createElement(at),b=[\/^\\\/([a-z]{2})([_-][a-z]{2})?(\\\/.*)?$\/g.exec(cl),\n\/^([a-z]{2})\\.\/.exec(ar),\/\\.([a-z]{2,})$\/.exec(ar)],c={at:\"de\",au:\"en\",ca:\"en\",cz:\n\"cs\",dk:\"da\",ee:\"et\",no:\"nb\",se:\"sv\",uk:\"en\"},d=de.scripts,e=d[d.length-1],f=0;\nfor(f of b){b=f?f[1]:n;if(f)break}b=b.length!=2?o:b;b=c[b]?c[b]:b;a.id=i;a.dataset.\nculture=b;a.src=`https:\/\/consent.cookiebot.com\/${o}\/cd.js`;e.parentNode.\ninsertBefore(a,e)}(document,location.pathname,location.hostname,\"script\",\n\"CookieDeclaration\",\"4d593826-00b9-41b4-94ef-88405def6e26\",\"IT\");<\/script>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Privacy policy Polaris S.R.L. (nel seguito, \u201cPolaris S.R.L.\u201d) fornisce agli utenti del sito web Polaris Shop (nel seguito, il \u201cSito\u201d, visitabile all\u2019indirizzo www.polarisshop.ch) le seguenti informazioni, nel rispetto dell\u2019articolo 13 Regolamento (UE) 2016\/679 (o General Data Protection Regulation, nel seguito \u201cG.D.P.R\u201d) e successiva normativa nazionale di adeguamento (nel seguito indicata, congiuntamente al G.D.P.R., come \u201cNormativa Privacy Applicabile\u201d). Durante la consultazione del Sito vengono, infatti, raccolte informazioni relative agli utenti, che costituiscono dati personali ai sensi della Normativa Privacy applicabile. Titolare del trattamento dei dati Titolare del trattamento dei dati personali \u00e8 Polaris S.R.L., con sede in Italia: sede legale in Via Trento, 13\/H a Sondrio (SO) e sede operativa in Via Stelvio, 24 a Poggiridenti (SO), e-mail info@polarisshop.ch e tel. +39 0342 513196. Tipi di dati trattati Di seguito sono specificati i dati che vengono trattati da Polaris S.R.L. nel caso in cui l\u2019utente utilizzi il Sito.L&#8217;utente si assume la responsabilit\u00e0 degli eventuali dati personali di terzi inseriti o pubblicati sul Sito, e garantisce di avere il diritto di comunicarli o diffonderli &#8211; liberando cos\u00ec Polaris S.R.L. da qualsiasi responsabilit\u00e0 verso i suddetti terzi. Dati personali acquisiti automaticamente in caso di visita al Sito Dati sulla navigazione. Polaris S.R.L. raccoglie automaticamente dati sul dispositivo (pc, tablet, telefono cellulare o altro dispositivo mobile) e la connessione utilizzati dall\u2019utente, tra i quali, ad esempio, l\u2019indirizzo IP, la data e l\u2019ora di accesso, le informazioni su hardware e software, le informazioni sugli eventi riguardanti il dispositivo, gli identificativi unici, i dati di crash. Dati sull&#8217;utilizzo del Sito. Polaris S.R.L. raccoglie informazioni sulle modalit\u00e0 con le quali l\u2019utente ha utilizzato il Sito, comprese, ad esempio, le pagine del Sito o altri contenuti visualizzati, le ricerche effettuate, le applicazioni di terze parti presenti sul Sito che vengono utilizzate dall\u2019utente e i link ad altri siti e applicazioni su cui l\u2019utente ha cliccato. Dati personali forniti direttamente dall\u2019utente a) Dati necessari per la creazione di un account Dati forniti per la creazione di un account. Se l\u2019utente, attraverso l\u2019icona o in fase di checkout decide di registrarsi al sito, Polaris S.R.L. raccoglie nome, cognome, indirizzo e-mail. Queste informazioni sono necessarie per consentire all\u2019utente di creare un account presso Polaris S.R.L.. Se l\u2019utente non intende fornire i suddetti dati, non potr\u00e0 creare la propria area riservata. b) Dati facoltativi Dati forniti mediante richieste di informazioni via e-mail. Se l\u2019utente, per richiedere informazioni, invia in modo esplicito e volontario posta elettronica agli indirizzi di Polaris S.R.L. indicati sul Sito, oppure utilizza il modulo disponibile nella sezione del sito \u201cContatti\u201d Polaris S.R.L. acquisisce nome, cognome e indirizzo e-mail. Finalit\u00e0 di trattamento Contribuire al funzionamento del Sito; fornire all\u2019utente i servizi che Polaris S.R.L. presta tramite il Sito; proteggere gli interessi vitali dell\u2019utente; rispettare la normativa vigente o perseguire altre esigenze di interesse pubblico I dati dell\u2019utente, infatti, vengono trattati: per far funzionare, misurare, migliorare e mantenere sicuri il Sito e i servizi resi tramite esso; per prevenire, rilevare e mitigare violazioni della sicurezza e attivit\u00e0 potenzialmente vietate o illegali. Perseguire i legittimi interessi di Polaris S.R.L. in modo tale che questi interessi non prevalgano sui diritti e sulle libert\u00e0 fondamentali dell\u2019utente I dati dell\u2019utente, infatti, vengono trattati: per identificare e risolvere i problemi riscontrati dall\u2019utente nell\u2019utilizzo del Sito (ad esempio, pagine bloccate o non funzionanti). Questi trattamenti tutelano l\u2019interesse di Polaris S.R.L. a mantenere il Sito funzionante ed efficiente. Essi, inoltre, non ledono i diritti e le libert\u00e0 fondamentali dell\u2019utente, in quanto sono trattamenti prevedibili e diffusi in ogni sito che permetta la creazione di account. Inoltre, tali trattamenti vanno altres\u00ec a vantaggio dell\u2019utente stesso, permettendo al Sito di continuare a funzionare. Social button Il Sito utilizza diversi link, che permettono agli utenti di visitare i profili Facebook e Instagram di Polaris Shop (vedi footer del Sito). Questi link &#8211; che si presentano come icone dei relativi social networks &#8211; non comportano l\u2019installazione di cookie di terze parti. Modalit\u00e0 di trattamento I dati personali dell\u2019utente sono trattati con strumenti, informatici o telematici, esclusivamente per le finalit\u00e0 per le quali sono stati raccolti (vedi sopra), e conservati per un periodo determinato secondo i criteri segnalati in questa privacy policy (vedi sotto).I dati personali potranno essere conosciuti e trattati dal personale di Polaris S.R.L., debitamente istruito circa le cautele da adottare previste dalla Normativa Privacy applicabile. Durata di trattamento Gli specifici tempi di conservazione dei dati personali dell\u2019utente sono documentati nel registro delle attivit\u00e0 di trattamento di Polaris S.R.L. (implementato ai sensi dell\u2019articolo 30 della G.D.P.R.).I dati personali dell\u2019utente vengono conservati (secondo i criteri di cui al considerando 39 e all\u2019art. 5, comma 1, lett. e) del G.D.P.R.) per un periodo necessario ad assicurare che il Sito funzioni, e che Polaris S.R.L. eroghi agli utenti i servizi prestati tramite il Sito. Tale periodo, in ogni caso, non pu\u00f2 eccedere i 10 anni dalla raccolta.I dati personali dell\u2019utente possono essere conservati per periodi maggiori di quelli appena visti solamente nel caso in ci\u00f2 sia necessario a Polaris S.R.L. per assolvere gli obblighi di legge ricadenti in capo ad essi o per tutelare un diritto in sede giudiziaria.Alla scadenza di tali termini di conservazione, i dati dell\u2019utente vengono cancellati, oppure resi anonimi in modo permanente. Comunicazione dei dati Polaris S.R.L. potrebbe comunicare i dati personali trattati ai soli soggetti e per le sole finalit\u00e0 di seguito indicati. Lotta agli atti illeciti e alle violazioni di sicurezza Polaris S.R.L. potrebbe comunicare i dati personali degli utenti a soggetti terzi che si occupano di prevenire, rilevare e mitigare atti potenzialmente illeciti e violazioni della sicurezza. Applicazione della legge, procedimenti giudiziari e modalit\u00e0 autorizzate dalla legge italiana Polaris S.R.L. potrebbe comunicare i dati personali degli utenti ad Autorit\u00e0 Giudiziarie, Pubbliche Autorit\u00e0 o terze parti autorizzate, nei casi in cui la legge lo prevede. Nonch\u00e9, in generale, nei casi in cui sia necessario per adempiere obblighi di legge o richieste verificate relative ad un&#8217;indagine penale o ad una presunta attivit\u00e0 illecita, oppure per rispondere a rivendicazioni altrui circa i diritti, la propriet\u00e0 o la sicurezza di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy policy - Polaris Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy policy - Polaris Shop\" \/>\n<meta property=\"og:description\" content=\"Privacy policy Polaris S.R.L. (nel seguito, \u201cPolaris S.R.L.\u201d) fornisce agli utenti del sito web Polaris Shop (nel seguito, il \u201cSito\u201d, visitabile all\u2019indirizzo www.polarisshop.ch) le seguenti informazioni, nel rispetto dell\u2019articolo 13 Regolamento (UE) 2016\/679 (o General Data Protection Regulation, nel seguito \u201cG.D.P.R\u201d) e successiva normativa nazionale di adeguamento (nel seguito indicata, congiuntamente al G.D.P.R., come \u201cNormativa Privacy Applicabile\u201d). Durante la consultazione del Sito vengono, infatti, raccolte informazioni relative agli utenti, che costituiscono dati personali ai sensi della Normativa Privacy applicabile. Titolare del trattamento dei dati Titolare del trattamento dei dati personali \u00e8 Polaris S.R.L., con sede in Italia: sede legale in Via Trento, 13\/H a Sondrio (SO) e sede operativa in Via Stelvio, 24 a Poggiridenti (SO), e-mail info@polarisshop.ch e tel. +39 0342 513196. Tipi di dati trattati Di seguito sono specificati i dati che vengono trattati da Polaris S.R.L. nel caso in cui l\u2019utente utilizzi il Sito.L&#8217;utente si assume la responsabilit\u00e0 degli eventuali dati personali di terzi inseriti o pubblicati sul Sito, e garantisce di avere il diritto di comunicarli o diffonderli &#8211; liberando cos\u00ec Polaris S.R.L. da qualsiasi responsabilit\u00e0 verso i suddetti terzi. Dati personali acquisiti automaticamente in caso di visita al Sito Dati sulla navigazione. Polaris S.R.L. raccoglie automaticamente dati sul dispositivo (pc, tablet, telefono cellulare o altro dispositivo mobile) e la connessione utilizzati dall\u2019utente, tra i quali, ad esempio, l\u2019indirizzo IP, la data e l\u2019ora di accesso, le informazioni su hardware e software, le informazioni sugli eventi riguardanti il dispositivo, gli identificativi unici, i dati di crash. Dati sull&#8217;utilizzo del Sito. Polaris S.R.L. raccoglie informazioni sulle modalit\u00e0 con le quali l\u2019utente ha utilizzato il Sito, comprese, ad esempio, le pagine del Sito o altri contenuti visualizzati, le ricerche effettuate, le applicazioni di terze parti presenti sul Sito che vengono utilizzate dall\u2019utente e i link ad altri siti e applicazioni su cui l\u2019utente ha cliccato. Dati personali forniti direttamente dall\u2019utente a) Dati necessari per la creazione di un account Dati forniti per la creazione di un account. Se l\u2019utente, attraverso l\u2019icona o in fase di checkout decide di registrarsi al sito, Polaris S.R.L. raccoglie nome, cognome, indirizzo e-mail. Queste informazioni sono necessarie per consentire all\u2019utente di creare un account presso Polaris S.R.L.. Se l\u2019utente non intende fornire i suddetti dati, non potr\u00e0 creare la propria area riservata. b) Dati facoltativi Dati forniti mediante richieste di informazioni via e-mail. Se l\u2019utente, per richiedere informazioni, invia in modo esplicito e volontario posta elettronica agli indirizzi di Polaris S.R.L. indicati sul Sito, oppure utilizza il modulo disponibile nella sezione del sito \u201cContatti\u201d Polaris S.R.L. acquisisce nome, cognome e indirizzo e-mail. Finalit\u00e0 di trattamento Contribuire al funzionamento del Sito; fornire all\u2019utente i servizi che Polaris S.R.L. presta tramite il Sito; proteggere gli interessi vitali dell\u2019utente; rispettare la normativa vigente o perseguire altre esigenze di interesse pubblico I dati dell\u2019utente, infatti, vengono trattati: per far funzionare, misurare, migliorare e mantenere sicuri il Sito e i servizi resi tramite esso; per prevenire, rilevare e mitigare violazioni della sicurezza e attivit\u00e0 potenzialmente vietate o illegali. Perseguire i legittimi interessi di Polaris S.R.L. in modo tale che questi interessi non prevalgano sui diritti e sulle libert\u00e0 fondamentali dell\u2019utente I dati dell\u2019utente, infatti, vengono trattati: per identificare e risolvere i problemi riscontrati dall\u2019utente nell\u2019utilizzo del Sito (ad esempio, pagine bloccate o non funzionanti). Questi trattamenti tutelano l\u2019interesse di Polaris S.R.L. a mantenere il Sito funzionante ed efficiente. Essi, inoltre, non ledono i diritti e le libert\u00e0 fondamentali dell\u2019utente, in quanto sono trattamenti prevedibili e diffusi in ogni sito che permetta la creazione di account. Inoltre, tali trattamenti vanno altres\u00ec a vantaggio dell\u2019utente stesso, permettendo al Sito di continuare a funzionare. Social button Il Sito utilizza diversi link, che permettono agli utenti di visitare i profili Facebook e Instagram di Polaris Shop (vedi footer del Sito). Questi link &#8211; che si presentano come icone dei relativi social networks &#8211; non comportano l\u2019installazione di cookie di terze parti. Modalit\u00e0 di trattamento I dati personali dell\u2019utente sono trattati con strumenti, informatici o telematici, esclusivamente per le finalit\u00e0 per le quali sono stati raccolti (vedi sopra), e conservati per un periodo determinato secondo i criteri segnalati in questa privacy policy (vedi sotto).I dati personali potranno essere conosciuti e trattati dal personale di Polaris S.R.L., debitamente istruito circa le cautele da adottare previste dalla Normativa Privacy applicabile. Durata di trattamento Gli specifici tempi di conservazione dei dati personali dell\u2019utente sono documentati nel registro delle attivit\u00e0 di trattamento di Polaris S.R.L. (implementato ai sensi dell\u2019articolo 30 della G.D.P.R.).I dati personali dell\u2019utente vengono conservati (secondo i criteri di cui al considerando 39 e all\u2019art. 5, comma 1, lett. e) del G.D.P.R.) per un periodo necessario ad assicurare che il Sito funzioni, e che Polaris S.R.L. eroghi agli utenti i servizi prestati tramite il Sito. Tale periodo, in ogni caso, non pu\u00f2 eccedere i 10 anni dalla raccolta.I dati personali dell\u2019utente possono essere conservati per periodi maggiori di quelli appena visti solamente nel caso in ci\u00f2 sia necessario a Polaris S.R.L. per assolvere gli obblighi di legge ricadenti in capo ad essi o per tutelare un diritto in sede giudiziaria.Alla scadenza di tali termini di conservazione, i dati dell\u2019utente vengono cancellati, oppure resi anonimi in modo permanente. Comunicazione dei dati Polaris S.R.L. potrebbe comunicare i dati personali trattati ai soli soggetti e per le sole finalit\u00e0 di seguito indicati. Lotta agli atti illeciti e alle violazioni di sicurezza Polaris S.R.L. potrebbe comunicare i dati personali degli utenti a soggetti terzi che si occupano di prevenire, rilevare e mitigare atti potenzialmente illeciti e violazioni della sicurezza. Applicazione della legge, procedimenti giudiziari e modalit\u00e0 autorizzate dalla legge italiana Polaris S.R.L. potrebbe comunicare i dati personali degli utenti ad Autorit\u00e0 Giudiziarie, Pubbliche Autorit\u00e0 o terze parti autorizzate, nei casi in cui la legge lo prevede. Nonch\u00e9, in generale, nei casi in cui sia necessario per adempiere obblighi di legge o richieste verificate relative ad un&#8217;indagine penale o ad una presunta attivit\u00e0 illecita, oppure per rispondere a rivendicazioni altrui circa i diritti, la propriet\u00e0 o la sicurezza di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Polaris Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-15T14:00:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/\",\"url\":\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/\",\"name\":\"Privacy policy - Polaris Shop\",\"isPartOf\":{\"@id\":\"https:\/\/www.polarisshop.ch\/#website\"},\"datePublished\":\"2023-05-03T10:21:56+00:00\",\"dateModified\":\"2023-09-15T14:00:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.polarisshop.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polarisshop.ch\/#website\",\"url\":\"https:\/\/www.polarisshop.ch\/\",\"name\":\"Polaris Shop\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.polarisshop.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.polarisshop.ch\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.polarisshop.ch\/#organization\",\"name\":\"Polaris Shop\",\"url\":\"https:\/\/www.polarisshop.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.polarisshop.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.polarisshop.ch\/wp-content\/uploads\/2023\/05\/logo-polaris.svg\",\"contentUrl\":\"https:\/\/www.polarisshop.ch\/wp-content\/uploads\/2023\/05\/logo-polaris.svg\",\"width\":1838,\"height\":400,\"caption\":\"Polaris Shop\"},\"image\":{\"@id\":\"https:\/\/www.polarisshop.ch\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy policy - Polaris Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy policy - Polaris Shop","og_description":"Privacy policy Polaris S.R.L. (nel seguito, \u201cPolaris S.R.L.\u201d) fornisce agli utenti del sito web Polaris Shop (nel seguito, il \u201cSito\u201d, visitabile all\u2019indirizzo www.polarisshop.ch) le seguenti informazioni, nel rispetto dell\u2019articolo 13 Regolamento (UE) 2016\/679 (o General Data Protection Regulation, nel seguito \u201cG.D.P.R\u201d) e successiva normativa nazionale di adeguamento (nel seguito indicata, congiuntamente al G.D.P.R., come \u201cNormativa Privacy Applicabile\u201d). Durante la consultazione del Sito vengono, infatti, raccolte informazioni relative agli utenti, che costituiscono dati personali ai sensi della Normativa Privacy applicabile. Titolare del trattamento dei dati Titolare del trattamento dei dati personali \u00e8 Polaris S.R.L., con sede in Italia: sede legale in Via Trento, 13\/H a Sondrio (SO) e sede operativa in Via Stelvio, 24 a Poggiridenti (SO), e-mail info@polarisshop.ch e tel. +39 0342 513196. Tipi di dati trattati Di seguito sono specificati i dati che vengono trattati da Polaris S.R.L. nel caso in cui l\u2019utente utilizzi il Sito.L&#8217;utente si assume la responsabilit\u00e0 degli eventuali dati personali di terzi inseriti o pubblicati sul Sito, e garantisce di avere il diritto di comunicarli o diffonderli &#8211; liberando cos\u00ec Polaris S.R.L. da qualsiasi responsabilit\u00e0 verso i suddetti terzi. Dati personali acquisiti automaticamente in caso di visita al Sito Dati sulla navigazione. Polaris S.R.L. raccoglie automaticamente dati sul dispositivo (pc, tablet, telefono cellulare o altro dispositivo mobile) e la connessione utilizzati dall\u2019utente, tra i quali, ad esempio, l\u2019indirizzo IP, la data e l\u2019ora di accesso, le informazioni su hardware e software, le informazioni sugli eventi riguardanti il dispositivo, gli identificativi unici, i dati di crash. Dati sull&#8217;utilizzo del Sito. Polaris S.R.L. raccoglie informazioni sulle modalit\u00e0 con le quali l\u2019utente ha utilizzato il Sito, comprese, ad esempio, le pagine del Sito o altri contenuti visualizzati, le ricerche effettuate, le applicazioni di terze parti presenti sul Sito che vengono utilizzate dall\u2019utente e i link ad altri siti e applicazioni su cui l\u2019utente ha cliccato. Dati personali forniti direttamente dall\u2019utente a) Dati necessari per la creazione di un account Dati forniti per la creazione di un account. Se l\u2019utente, attraverso l\u2019icona o in fase di checkout decide di registrarsi al sito, Polaris S.R.L. raccoglie nome, cognome, indirizzo e-mail. Queste informazioni sono necessarie per consentire all\u2019utente di creare un account presso Polaris S.R.L.. Se l\u2019utente non intende fornire i suddetti dati, non potr\u00e0 creare la propria area riservata. b) Dati facoltativi Dati forniti mediante richieste di informazioni via e-mail. Se l\u2019utente, per richiedere informazioni, invia in modo esplicito e volontario posta elettronica agli indirizzi di Polaris S.R.L. indicati sul Sito, oppure utilizza il modulo disponibile nella sezione del sito \u201cContatti\u201d Polaris S.R.L. acquisisce nome, cognome e indirizzo e-mail. Finalit\u00e0 di trattamento Contribuire al funzionamento del Sito; fornire all\u2019utente i servizi che Polaris S.R.L. presta tramite il Sito; proteggere gli interessi vitali dell\u2019utente; rispettare la normativa vigente o perseguire altre esigenze di interesse pubblico I dati dell\u2019utente, infatti, vengono trattati: per far funzionare, misurare, migliorare e mantenere sicuri il Sito e i servizi resi tramite esso; per prevenire, rilevare e mitigare violazioni della sicurezza e attivit\u00e0 potenzialmente vietate o illegali. Perseguire i legittimi interessi di Polaris S.R.L. in modo tale che questi interessi non prevalgano sui diritti e sulle libert\u00e0 fondamentali dell\u2019utente I dati dell\u2019utente, infatti, vengono trattati: per identificare e risolvere i problemi riscontrati dall\u2019utente nell\u2019utilizzo del Sito (ad esempio, pagine bloccate o non funzionanti). Questi trattamenti tutelano l\u2019interesse di Polaris S.R.L. a mantenere il Sito funzionante ed efficiente. Essi, inoltre, non ledono i diritti e le libert\u00e0 fondamentali dell\u2019utente, in quanto sono trattamenti prevedibili e diffusi in ogni sito che permetta la creazione di account. Inoltre, tali trattamenti vanno altres\u00ec a vantaggio dell\u2019utente stesso, permettendo al Sito di continuare a funzionare. Social button Il Sito utilizza diversi link, che permettono agli utenti di visitare i profili Facebook e Instagram di Polaris Shop (vedi footer del Sito). Questi link &#8211; che si presentano come icone dei relativi social networks &#8211; non comportano l\u2019installazione di cookie di terze parti. Modalit\u00e0 di trattamento I dati personali dell\u2019utente sono trattati con strumenti, informatici o telematici, esclusivamente per le finalit\u00e0 per le quali sono stati raccolti (vedi sopra), e conservati per un periodo determinato secondo i criteri segnalati in questa privacy policy (vedi sotto).I dati personali potranno essere conosciuti e trattati dal personale di Polaris S.R.L., debitamente istruito circa le cautele da adottare previste dalla Normativa Privacy applicabile. Durata di trattamento Gli specifici tempi di conservazione dei dati personali dell\u2019utente sono documentati nel registro delle attivit\u00e0 di trattamento di Polaris S.R.L. (implementato ai sensi dell\u2019articolo 30 della G.D.P.R.).I dati personali dell\u2019utente vengono conservati (secondo i criteri di cui al considerando 39 e all\u2019art. 5, comma 1, lett. e) del G.D.P.R.) per un periodo necessario ad assicurare che il Sito funzioni, e che Polaris S.R.L. eroghi agli utenti i servizi prestati tramite il Sito. Tale periodo, in ogni caso, non pu\u00f2 eccedere i 10 anni dalla raccolta.I dati personali dell\u2019utente possono essere conservati per periodi maggiori di quelli appena visti solamente nel caso in ci\u00f2 sia necessario a Polaris S.R.L. per assolvere gli obblighi di legge ricadenti in capo ad essi o per tutelare un diritto in sede giudiziaria.Alla scadenza di tali termini di conservazione, i dati dell\u2019utente vengono cancellati, oppure resi anonimi in modo permanente. Comunicazione dei dati Polaris S.R.L. potrebbe comunicare i dati personali trattati ai soli soggetti e per le sole finalit\u00e0 di seguito indicati. Lotta agli atti illeciti e alle violazioni di sicurezza Polaris S.R.L. potrebbe comunicare i dati personali degli utenti a soggetti terzi che si occupano di prevenire, rilevare e mitigare atti potenzialmente illeciti e violazioni della sicurezza. Applicazione della legge, procedimenti giudiziari e modalit\u00e0 autorizzate dalla legge italiana Polaris S.R.L. potrebbe comunicare i dati personali degli utenti ad Autorit\u00e0 Giudiziarie, Pubbliche Autorit\u00e0 o terze parti autorizzate, nei casi in cui la legge lo prevede. Nonch\u00e9, in generale, nei casi in cui sia necessario per adempiere obblighi di legge o richieste verificate relative ad un&#8217;indagine penale o ad una presunta attivit\u00e0 illecita, oppure per rispondere a rivendicazioni altrui circa i diritti, la propriet\u00e0 o la sicurezza di [&hellip;]","og_url":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/","og_site_name":"Polaris Shop","article_modified_time":"2023-09-15T14:00:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/","url":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/","name":"Privacy policy - Polaris Shop","isPartOf":{"@id":"https:\/\/www.polarisshop.ch\/#website"},"datePublished":"2023-05-03T10:21:56+00:00","dateModified":"2023-09-15T14:00:10+00:00","breadcrumb":{"@id":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polarisshop.ch\/it\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.polarisshop.ch\/it\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.polarisshop.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy policy"}]},{"@type":"WebSite","@id":"https:\/\/www.polarisshop.ch\/#website","url":"https:\/\/www.polarisshop.ch\/","name":"Polaris Shop","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.polarisshop.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polarisshop.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.polarisshop.ch\/#organization","name":"Polaris Shop","url":"https:\/\/www.polarisshop.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.polarisshop.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.polarisshop.ch\/wp-content\/uploads\/2023\/05\/logo-polaris.svg","contentUrl":"https:\/\/www.polarisshop.ch\/wp-content\/uploads\/2023\/05\/logo-polaris.svg","width":1838,"height":400,"caption":"Polaris Shop"},"image":{"@id":"https:\/\/www.polarisshop.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/pages\/297"}],"collection":[{"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/comments?post=297"}],"version-history":[{"count":28,"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/pages\/297\/revisions"}],"predecessor-version":[{"id":882,"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/pages\/297\/revisions\/882"}],"wp:attachment":[{"href":"https:\/\/www.polarisshop.ch\/it\/wp-json\/wp\/v2\/media?parent=297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}